{"id":360846,"date":"2026-09-02T12:04:35","date_gmt":"2026-09-02T12:04:35","guid":{"rendered":"https:\/\/www.evearly.news\/en\/tesla-chinas-august-wholesale-sales-total-86166-snapping-3-month-sequential-gain-streak\/"},"modified":"2026-09-02T12:04:35","modified_gmt":"2026-09-02T12:04:35","slug":"tesla-chinas-august-wholesale-sales-total-86166-snapping-3-month-sequential-gain-streak","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/en\/tesla-chinas-august-wholesale-sales-total-86166-snapping-3-month-sequential-gain-streak\/","title":{"rendered":"Tesla China&#8217;s August wholesale sales total 86,166, snapping 3-month sequential gain streak"},"content":{"rendered":"<p><img src='https:\/\/www.evearly.news\/en\/wp-content\/uploads\/sites\/7\/2026\/09\/tesla-chinas-august-wholesale-sales-total-86166-snapping-3-month-sequential-gain-streak.jpg' alt='' ><br \/>Tesla China&#8217;s August wholesale sales rose 3.57% year-on-year but fell 7.92% from July. <a href=https:\/\/cnevpost.com\/2026\/09\/02\/tesla-china-aug-2026-wholesale-sales\/ target='blank'>Read more&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.evearly.news\/en\/wp-content\/uploads\/sites\/7\/2026\/09\/tesla-chinas-august-wholesale-sales-total-86166-snapping-3-month-sequential-gain-streak.jpg\" alt=\"\"><br \/>Tesla China&#8217;s August wholesale sales rose 3.57% year-on-year but fell 7.92% from July.<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/en\/tesla-chinas-august-wholesale-sales-total-86166-snapping-3-month-sequential-gain-streak\/\"><\/a><\/p>\n","protected":false},"author":31,"featured_media":360847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-360846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cnevpost"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/posts\/360846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/comments?post=360846"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/posts\/360846\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/media\/360847"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/media?parent=360846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/categories?post=360846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/en\/wp-json\/wp\/v2\/tags?post=360846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}