{"id":238430,"date":"2023-04-19T18:32:00","date_gmt":"2023-04-19T16:32:00","guid":{"rendered":"https:\/\/news.evearly.com\/actualite-smart-3-le-suv-electrique-se-decline-en-coupe-fastback\/"},"modified":"2023-04-19T18:32:00","modified_gmt":"2023-04-19T16:32:00","slug":"actualite-smart-3-le-suv-electrique-se-decline-en-coupe-fastback","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/actualite-smart-3-le-suv-electrique-se-decline-en-coupe-fastback\/","title":{"rendered":"Actualit\u00e9 : Smart #3 : le SUV \u00e9lectrique se d\u00e9cline en coup\u00e9 fastback"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/news.evearly.com\/wp-content\/uploads\/2023\/04\/actualite-smart-3-le-suv-electrique-se-decline-en-coupe-fastback.jpg\" \/>Smart d\u00e9voile les lignes et l&rsquo;int\u00e9rieur de son futur SUV coup\u00e9 \u00e9lectrique Smart #3. Reposant sur la plateforme du Smart #1, il sera pr\u00e9sent\u00e9 en Europe \u00e0 l\u2019IAA en septembre\u00a02023. <a href=\"https:\/\/www.lesnumeriques.com\/voiture\/smart-3-le-suv-electrique-se-decline-en-coupe-fastback-n208978.html\" target='bwindow' rel=\"noopener\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Smart d\u00e9voile les lignes et l&rsquo;int\u00e9rieur de son futur SUV coup\u00e9 \u00e9lectrique Smart #3. Reposant sur la plateforme du Smart #1, il sera pr\u00e9sent\u00e9 en Europe \u00e0 l\u2019IAA en septembre\u00a02023&#8230;. <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/actualite-smart-3-le-suv-electrique-se-decline-en-coupe-fastback\/\"><\/a><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-238430","post","type-post","status-publish","format-standard","hentry","category-lesnumeriques"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/238430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=238430"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/238430\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=238430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=238430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=238430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}