{"id":282022,"date":"2024-06-07T09:56:05","date_gmt":"2024-06-07T07:56:05","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/cette-tesla-parcourt-700-000-km-avec-la-batterie-dorigine-est-ce-la-fin-du-thermique\/"},"modified":"2024-06-07T09:56:05","modified_gmt":"2024-06-07T07:56:05","slug":"cette-tesla-parcourt-700-000-km-avec-la-batterie-dorigine-est-ce-la-fin-du-thermique","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/cette-tesla-parcourt-700-000-km-avec-la-batterie-dorigine-est-ce-la-fin-du-thermique\/","title":{"rendered":"Cette Tesla parcourt 700 000 km avec la batterie d\u2019origine, est-ce la fin du thermique ?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2024\/06\/cette-tesla-parcourt-700-000-km-avec-la-batterie-dorigine-est-ce-la-fin-du-thermique.jpg\"><br \/>Lorsqu&rsquo;il s&rsquo;agit d&rsquo;accumuler des kilom\u00e9trages astronomiques, les v\u00e9hicules \u00e9lectriques sont souvent injustement consid\u00e9r\u00e9s comme intrins\u00e8quement moins durables que leurs homologues \u00e0 essence. Cependant, une Tesla Model S 2016 du Royaume-Uni brise ce mythe. Un conducteur de Tesla Model S de&#8230; <a href=\"https:\/\/www.phonandroid.com\/cette-tesla-parcourt-700-000-km-avec-la-batterie-dorigine-est-ce-la-fin-du-thermique.html\" target=\"blank\" rel=\"noopener\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu&rsquo;il s&rsquo;agit d&rsquo;accumuler des kilom\u00e9trages astronomiques, les v\u00e9hicules \u00e9lectriques sont souvent injustement consid\u00e9r\u00e9s comme intrins\u00e8quement moins durables que leurs homologues \u00e0 essence. Cependant, une Tesla Model S 2016 du Royaume-Uni brise ce mythe. Un conducteur de Tesla Model S de&#8230;&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/cette-tesla-parcourt-700-000-km-avec-la-batterie-dorigine-est-ce-la-fin-du-thermique\/\"><\/a><\/p>\n","protected":false},"author":17,"featured_media":282023,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-282022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-phonandroid"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/282022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=282022"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/282022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/282023"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=282022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=282022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=282022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}