{"id":291157,"date":"2024-11-14T11:23:24","date_gmt":"2024-11-14T10:23:24","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/voici-les-coulisses-de-la-decision-qui-pourrait-sauver-volkswagen-sur-la-voiture-electrique\/"},"modified":"2024-11-14T11:23:24","modified_gmt":"2024-11-14T10:23:24","slug":"voici-les-coulisses-de-la-decision-qui-pourrait-sauver-volkswagen-sur-la-voiture-electrique","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/voici-les-coulisses-de-la-decision-qui-pourrait-sauver-volkswagen-sur-la-voiture-electrique\/","title":{"rendered":"Voici les coulisses de la d\u00e9cision qui pourrait sauver Volkswagen sur la voiture \u00e9lectrique"},"content":{"rendered":"<p><img width=\"1200\" height=\"800\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2024\/11\/voici-les-coulisses-de-la-decision-qui-pourrait-sauver-volkswagen-sur-la-voiture-electrique.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/<br \/>\nVolkswagen vient tout juste de cr\u00e9er une nouvelle entreprise d\u00e9di\u00e9e aux voitures \u00e9lectriques avec le jeune constructeur am\u00e9ricain Rivian. Ce projet permettra \u00e0 la firme allemande de combler certaines de ses lacunes, voire m\u00eame d&rsquo;\u00e9viter le risque de disparition \u00e0 terme. Et on conna\u00eet d\u00e9sormais les coulisses de l&rsquo;histoire.<br \/>\n <a href=\"https:\/\/www.frandroid.com\/marques\/volkswagen\/2401682_voici-les-coulisses-de-la-decision-qui-pourrait-sauver-volkswagen-sur-la-voiture-electrique\" target='bwindow' rel=\"noopener\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;img width=&quot;1200&quot; height=&quot;800&quot; src=&quot;https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2024\/11\/voici-les-coulisses-de-la-decision-qui-pourrait-sauver-volkswagen-sur-la-voiture-electrique.jpg&quot; class=&quot;attachment-large size-large wp-post-image&quot; alt=&quot;&quot; decoding=&quot;async&quot; loading=&quot;lazy&quot; \/<br \/>\nVolkswagen vient tout juste de cr\u00e9er une nouvelle entreprise d\u00e9di\u00e9e aux voitures \u00e9lectriques avec le jeune constructeur am\u00e9ricain Rivian. Ce projet permettra \u00e0 la firme allemande de combler certaines de ses lacunes, voire m\u00eame d&rsquo;\u00e9viter le risque de disparition \u00e0 terme. Et on conna\u00eet d\u00e9sormais les coulisses de l&rsquo;histoire.\n<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/voici-les-coulisses-de-la-decision-qui-pourrait-sauver-volkswagen-sur-la-voiture-electrique\/\"><\/a><\/p>\n","protected":false},"author":6,"featured_media":291158,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-291157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frandroid"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/291157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=291157"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/291157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/291158"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=291157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=291157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=291157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}