{"id":291471,"date":"2024-11-20T08:50:05","date_gmt":"2024-11-20T07:50:05","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge\/"},"modified":"2024-11-20T08:50:05","modified_gmt":"2024-11-20T07:50:05","slug":"vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge\/","title":{"rendered":"Vision Digitale Energies : Des solutions globales pour les bornes de recharge"},"content":{"rendered":"<p><img width=\"1000\" height=\"560\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2024\/11\/vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Vision Digitale Energies\" decoding=\"async\" fetchpriority=\"high\" srcset=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2024\/11\/vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge.png 1000w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2024\/11\/vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge-1.png 300w, https:\/\/www.avem.fr\/wp-content\/uploads\/2024\/11\/visuel-couverture-768x430.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>Vision Digitale Energies, nouvel adh\u00e9rent de l\u2019AVEM, se distingue par son expertise dans l\u2019installation de bornes de recharge pour v\u00e9hicules \u00e9lectriques. Filiale du groupe Vision Digitale, l\u2019entreprise propose des solutions compl\u00e8tes et personnalis\u00e9es pour r\u00e9pondre aux besoins des particuliers, copropri\u00e9t\u00e9s, entreprises, et collectivit\u00e9s. Une entreprise n\u00e9e de la passion pour [\u2026] <a href=https:\/\/www.avem.fr\/2024\/11\/20\/vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge\/ target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"560\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2024\/11\/vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Vision Digitale Energies\" \/>Vision Digitale Energies, nouvel adh\u00e9rent de l\u2019AVEM, se distingue par son expertise dans l\u2019installation de bornes de recharge pour v\u00e9hicules \u00e9lectriques. Filiale du groupe Vision Digitale, l\u2019entreprise propose des solutions compl\u00e8tes et personnalis\u00e9es pour r\u00e9pondre aux besoins des particuliers, copropri\u00e9t\u00e9s, entreprises, et collectivit\u00e9s. Une entreprise n\u00e9e de la passion pour [\u2026] <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/vision-digitale-energies-des-solutions-globales-pour-les-bornes-de-recharge\/\"><\/a><\/p>\n","protected":false},"author":3,"featured_media":291472,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-291471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avem"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/291471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=291471"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/291471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/291472"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=291471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=291471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=291471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}