{"id":295230,"date":"2025-01-23T10:23:15","date_gmt":"2025-01-23T09:23:15","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques\/"},"modified":"2025-01-23T10:23:15","modified_gmt":"2025-01-23T09:23:15","slug":"ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques\/","title":{"rendered":"Ventes de voitures : d\u00e9buts mitig\u00e9s pour les Peugeot 3008 et Renault Sc\u00e9nic \u00e9lectriques"},"content":{"rendered":"<p><img decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/01\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques.png\" class=\"attachment-1200x800 size-1200x800 wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/01\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques.png 1600w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/01\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques-1.png 1024w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/01\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques-2.png 768w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/01\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques-3.png 1536w, https:\/\/cdn.automobile-propre.com\/uploads\/2024\/05\/Peugeot-e-3008-vs-Renault-Scenic-e-tech-5-620x349.png 620w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><br \/>\nLanc\u00e9s en 2024, les Peugeot e-3008 et Renault Sc\u00e9nic E-Tech ne brillent pas encore sur le march\u00e9 des SUV \u00e9lectriques.\u2026\u00a0<a href=https:\/\/www.automobile-propre.com\/articles\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques\/ target='bwindow'>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/ventes-de-voitures-debuts-mitiges-pour-les-peugeot-3008-et-renault-scenic-electriques\/\"><\/a><\/p>\n","protected":false},"author":8,"featured_media":295231,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-295230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automobile-propre"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/295230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=295230"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/295230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/295231"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=295230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=295230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=295230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}