{"id":296406,"date":"2025-02-11T14:33:20","date_gmt":"2025-02-11T13:33:20","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/ce-graphique-prouve-a-quel-point-les-voitures-electriques-chinoises-sont-plus-cheres-en-europe-quen-chine\/"},"modified":"2025-02-11T14:33:20","modified_gmt":"2025-02-11T13:33:20","slug":"ce-graphique-prouve-a-quel-point-les-voitures-electriques-chinoises-sont-plus-cheres-en-europe-quen-chine","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/ce-graphique-prouve-a-quel-point-les-voitures-electriques-chinoises-sont-plus-cheres-en-europe-quen-chine\/","title":{"rendered":"Ce graphique prouve \u00e0 quel point les voitures \u00e9lectriques chinoises sont plus ch\u00e8res en Europe qu\u2019en Chine"},"content":{"rendered":"<p><img width=\"1200\" height=\"675\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/02\/ce-graphique-prouve-a-quel-point-les-voitures-electriques-chinoises-sont-plus-cheres-en-europe-quen-chine.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/<br \/>\nEn passe de d\u00e9passer Tesla en termes de vente de voitures \u00e9lectriques, BYD a mis au point une strat\u00e9gie particuli\u00e8rement agressive. Le num\u00e9ro 2 mondial mise notamment sur des prix tr\u00e8s bas, et cela semble d\u00e9j\u00e0 porter ses fruits.<br \/>\n <a href=https:\/\/www.frandroid.com\/marques\/byd\/2500717_ce-graphique-prouve-a-quel-point-les-voitures-electriques-chinoises-sont-plus-cheres-en-europe-quen-chine target='blank'>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;img width=&quot;1200&quot; height=&quot;675&quot; src=&quot;https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/02\/ce-graphique-prouve-a-quel-point-les-voitures-electriques-chinoises-sont-plus-cheres-en-europe-quen-chine.jpg&quot; class=&quot;attachment-full size-full wp-post-image&quot; alt=&quot;&quot; decoding=&quot;async&quot; loading=&quot;lazy&quot; \/<br \/>\nEn passe de d\u00e9passer Tesla en termes de vente de voitures \u00e9lectriques, BYD a mis au point une strat\u00e9gie particuli\u00e8rement agressive. Le num\u00e9ro 2 mondial mise notamment sur des prix tr\u00e8s bas, et cela semble d\u00e9j\u00e0 porter ses fruits.\n<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/ce-graphique-prouve-a-quel-point-les-voitures-electriques-chinoises-sont-plus-cheres-en-europe-quen-chine\/\"><\/a><\/p>\n","protected":false},"author":6,"featured_media":296407,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-296406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frandroid"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/296406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=296406"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/296406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/296407"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=296406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=296406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=296406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}