{"id":297304,"date":"2025-02-26T11:02:03","date_gmt":"2025-02-26T10:02:03","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/byd-se-montre-plus-agressif-sur-les-prix-de-latto-2-a-moins-de-30-000-e\/"},"modified":"2025-02-26T11:02:03","modified_gmt":"2025-02-26T10:02:03","slug":"byd-se-montre-plus-agressif-sur-les-prix-de-latto-2-a-moins-de-30-000-e","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/byd-se-montre-plus-agressif-sur-les-prix-de-latto-2-a-moins-de-30-000-e\/","title":{"rendered":"BYD se montre plus agressif sur les prix de l\u2019Atto 2 \u00e0 moins de 30 000 \u20ac"},"content":{"rendered":"<p><img loading=\"lazy\" width=\"1200\" height=\"675\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/02\/byd-se-montre-plus-agressif-sur-les-prix-de-latto-2-a-moins-de-30-000-e.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" \/><br \/>\nBYD veut marquer les esprits avec le lancement de l\u2019Atto 2, un SUV urbain annonc\u00e9 \u00e0 partir de 28 990 \u20ac. Si le mod\u00e8le chinois affiche le prix le plus bas de la gamme de la marque, la concurrence europ\u00e9enne n\u2019a pas dit son dernier mot.<br \/>\n <a href=https:\/\/www.numerama.com\/vroom\/1912855-byd-se-montre-plus-agressif-sur-les-prix-de-latto-2-a-moins-de-30-000-e.html target='bwindow'>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/byd-se-montre-plus-agressif-sur-les-prix-de-latto-2-a-moins-de-30-000-e\/\"><\/a><\/p>\n","protected":false},"author":16,"featured_media":297305,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-297304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-numerama"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/297304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=297304"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/297304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/297305"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=297304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=297304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=297304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}