{"id":298385,"date":"2025-03-12T11:27:08","date_gmt":"2025-03-12T10:27:08","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/trump-defend-tesla-et-veut-punir-les-manifestants-comme-des-terroristes\/"},"modified":"2025-03-12T11:27:08","modified_gmt":"2025-03-12T10:27:08","slug":"trump-defend-tesla-et-veut-punir-les-manifestants-comme-des-terroristes","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/trump-defend-tesla-et-veut-punir-les-manifestants-comme-des-terroristes\/","title":{"rendered":"Trump d\u00e9fend Tesla et veut punir les manifestants comme des terroristes"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/03\/trump-defend-tesla-et-veut-punir-les-manifestants-comme-des-terroristes.jpg\"><br \/>Les tensions autour de Tesla continuent de monter. Apr\u00e8s des manifestations et des actes de vandalisme contre la marque, Donald Trump promet de s\u00e9vir. Le pr\u00e9sident am\u00e9ricain affirme qu\u2019il fera classer ces attaques comme du terrorisme int\u00e9rieur. Une d\u00e9claration qui&#8230; <a href=https:\/\/www.phonandroid.com\/trump-defend-tesla-et-veut-punir-les-manifestants-comme-des-terroristes.html target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les tensions autour de Tesla continuent de monter. Apr\u00e8s des manifestations et des actes de vandalisme contre la marque, Donald Trump promet de s\u00e9vir. Le pr\u00e9sident am\u00e9ricain affirme qu\u2019il fera classer ces attaques comme du terrorisme int\u00e9rieur. Une d\u00e9claration qui&#8230;&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/trump-defend-tesla-et-veut-punir-les-manifestants-comme-des-terroristes\/\"><\/a><\/p>\n","protected":false},"author":17,"featured_media":298386,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-298385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-phonandroid"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/298385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=298385"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/298385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/298386"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=298385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=298385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=298385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}