{"id":301252,"date":"2025-04-25T09:50:07","date_gmt":"2025-04-25T07:50:07","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie\/"},"modified":"2025-04-25T09:50:07","modified_gmt":"2025-04-25T07:50:07","slug":"1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie\/","title":{"rendered":"1 000 nouveaux autobus scolaires \u00e9lectriques pour la Californie"},"content":{"rendered":"<p><img width=\"1000\" height=\"563\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/04\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Californie V2X autobus scolaires\" decoding=\"async\" fetchpriority=\"high\" srcset=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/04\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie.jpg 1000w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/04\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie-1.jpg 300w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/04\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie-2.jpg 998w, https:\/\/www.avem.fr\/wp-content\/uploads\/2024\/01\/ACTE0102_V2XScolCalif-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>Une enveloppe de 500 millions de dollars constitu\u00e9e par l\u2019Etat de Californie va servir \u00e0 financer le d\u00e9ploiement de 1 000 nouveaux autobus scolaires sur le territoire ainsi que leurs infrastructures de recharge. \u00a0 D\u00e9j\u00e0 2 300 bus scolaires financ\u00e9s Alors que la politique am\u00e9ricaine est plus qu\u2019incertaine actuellement concernant [\u2026] <a href=https:\/\/www.avem.fr\/2025\/04\/25\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie\/ target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/04\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Californie V2X autobus scolaires\" \/>Une enveloppe de 500 millions de dollars constitu\u00e9e par l\u2019Etat de Californie va servir \u00e0 financer le d\u00e9ploiement de 1 000 nouveaux autobus scolaires sur le territoire ainsi que leurs infrastructures de recharge. \u00a0 D\u00e9j\u00e0 2 300 bus scolaires financ\u00e9s Alors que la politique am\u00e9ricaine est plus qu\u2019incertaine actuellement concernant [\u2026] <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/1-000-nouveaux-autobus-scolaires-electriques-pour-la-californie\/\"><\/a><\/p>\n","protected":false},"author":3,"featured_media":301253,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-301252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avem"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/301252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=301252"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/301252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/301253"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=301252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=301252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=301252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}