{"id":304151,"date":"2025-06-16T09:00:05","date_gmt":"2025-06-16T07:00:05","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech\/"},"modified":"2025-06-16T09:00:05","modified_gmt":"2025-06-16T07:00:05","slug":"vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech\/","title":{"rendered":"Vision 4rescue, le v\u00e9hicule des services d\u2019urgence du futur se d\u00e9voile \u00e0 VivaTech"},"content":{"rendered":"<p><img width=\"1000\" height=\"563\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Vision 4rescue Renault VivaTech\" decoding=\"async\" fetchpriority=\"high\" srcset=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech.jpg 1000w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech-1.jpg 300w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech-2.jpg 998w, https:\/\/www.avem.fr\/wp-content\/uploads\/2025\/06\/Vision-4rescue-Une-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>L\u2019\u00e9dition 2025 de VivaTech, le salon qui explore les nouvelles fronti\u00e8res de l\u2019innovation a ferm\u00e9 ses portes ce week-end. Depuis plusieurs ann\u00e9es, Renault et ses partenaires de la Software R\u00e9publique choisissent ce salon pour y pr\u00e9senter un concept-car innovant. Cette ann\u00e9e, ils d\u00e9voilent Vision 4rescue, un v\u00e9hicule int\u00e9grant un \u00e9cosyst\u00e8me [\u2026] <a href=https:\/\/www.avem.fr\/2025\/06\/16\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech\/ target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Vision 4rescue Renault VivaTech\" \/>L\u2019\u00e9dition 2025 de VivaTech, le salon qui explore les nouvelles fronti\u00e8res de l\u2019innovation a ferm\u00e9 ses portes ce week-end. Depuis plusieurs ann\u00e9es, Renault et ses partenaires de la Software R\u00e9publique choisissent ce salon pour y pr\u00e9senter un concept-car innovant. Cette ann\u00e9e, ils d\u00e9voilent Vision 4rescue, un v\u00e9hicule int\u00e9grant un \u00e9cosyst\u00e8me [\u2026] <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/vision-4rescue-le-vehicule-des-services-durgence-du-futur-se-devoile-a-vivatech\/\"><\/a><\/p>\n","protected":false},"author":3,"featured_media":304152,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-304151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avem"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=304151"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/304152"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=304151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=304151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=304151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}