{"id":304697,"date":"2025-06-26T12:07:48","date_gmt":"2025-06-26T10:07:48","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/les-ventes-de-voitures-electriques-dans-le-monde-continuent-de-croitre\/"},"modified":"2025-06-27T17:16:51","modified_gmt":"2025-06-27T15:16:51","slug":"les-ventes-de-voitures-electriques-dans-le-monde-continuent-de-croitre","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/les-ventes-de-voitures-electriques-dans-le-monde-continuent-de-croitre\/","title":{"rendered":"Les ventes de voitures \u00e9lectriques dans le monde continuent de cro\u00eetre"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/cdn.motor1.com\/images\/mgl\/G3eR3E\/s3\/l-auto-elettrica-nel-mondo.jpg\" alt=\"Les ventes de voitures \u00e9lectriques dans le monde continuent de cro\u00eetre\" \/><br \/>\nPr\u00e9vision du BNEF : fin 2025, il y aura 22 millions d&rsquo;immatriculations de voitures enti\u00e8rement \u00e9lectriques et hybrides rechargeables. Mais les \u00c9tats-Unis ralentissent. <a href=\"https:\/\/insideevs.fr\/news\/763771\/ventes-voitures-%C3%A9lectriques-monde-augmentent\/\" target=\"_blank\" rel=\"noopener\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;img src=&quot;&lt;htm4<br \/>Pr\u00e9vision du BNEF : fin 2025, il y aura 22 millions d&rsquo;immatriculations de voitures enti\u00e8rement \u00e9lectriques et hybrides rechargeables. Mais les \u00c9tats-Unis ralentissent.<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/les-ventes-de-voitures-electriques-dans-le-monde-continuent-de-croitre\/\"><\/a><\/p>\n","protected":false},"author":14,"featured_media":304698,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-304697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insideevs"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=304697"}],"version-history":[{"count":1,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304697\/revisions"}],"predecessor-version":[{"id":304810,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304697\/revisions\/304810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/304698"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=304697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=304697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=304697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}