{"id":304703,"date":"2025-06-26T12:22:10","date_gmt":"2025-06-26T10:22:10","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/ce-concept-car-electrique-mercedes-semble-setre-echappe-de-gta\/"},"modified":"2025-06-26T12:22:10","modified_gmt":"2025-06-26T10:22:10","slug":"ce-concept-car-electrique-mercedes-semble-setre-echappe-de-gta","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/ce-concept-car-electrique-mercedes-semble-setre-echappe-de-gta\/","title":{"rendered":"Ce concept-car \u00e9lectrique Mercedes semble s\u2019\u00eatre \u00e9chapp\u00e9 de GTA"},"content":{"rendered":"<p><img width=\"1200\" height=\"675\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/ce-concept-car-electrique-mercedes-semble-setre-echappe-de-gta.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><br \/>\nMercedes officialise le Concept AMG GT XX. C&rsquo;est un avant-go\u00fbt de ce que sera la future berline quatre portes AMG 100 % \u00e9lectrique, qui viendra se mesurer \u00e0 la Porsche Taycan. Au programme : une puissance d\u00e9lirante de 1 360 ch et une allure \u00e0 tomber par terre.<br \/>\n <a href=https:\/\/www.numerama.com\/vroom\/1998917-ce-concept-car-electrique-mercedes-semble-setre-echappe-de-gta.html target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/ce-concept-car-electrique-mercedes-semble-setre-echappe-de-gta\/\"><\/a><\/p>\n","protected":false},"author":16,"featured_media":304704,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-304703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-numerama"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=304703"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/304704"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=304703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=304703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=304703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}