{"id":304978,"date":"2025-07-01T09:00:07","date_gmt":"2025-07-01T07:00:07","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18\/"},"modified":"2025-07-01T09:00:07","modified_gmt":"2025-07-01T07:00:07","slug":"norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18\/","title":{"rendered":"Norev reproduit la Renault 4 E-Tech au 1\/64, 1\/43 et 1\/18"},"content":{"rendered":"<p><img width=\"1000\" height=\"563\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Renault 4 E-Tech Norev au 1\/18\" decoding=\"async\" fetchpriority=\"high\" srcset=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18.jpg 1000w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18-1.jpg 300w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18-2.jpg 998w, https:\/\/www.avem.fr\/wp-content\/uploads\/2025\/06\/ACTF0701_NorevR4-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>Le fabricant des mod\u00e8les r\u00e9duits de notre enfance se positionne un peu plus sur l\u2019\u00e9lectrique. La 4 E-Tech semble bien l\u2019inspirer, au point m\u00eame d\u2019en proposer une exclusivit\u00e9 Web au 1\/18e, limit\u00e9e \u00e0 300 exemplaires. \u00a0 D\u00e9couverte ou non Les collectionneurs de miniatures repr\u00e9sentant des voitures \u00e9lectriques sont-ils nombreux ? [\u2026] <a href=https:\/\/www.avem.fr\/2025\/07\/01\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18\/ target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Renault 4 E-Tech Norev au 1\/18\" \/>Le fabricant des mod\u00e8les r\u00e9duits de notre enfance se positionne un peu plus sur l\u2019\u00e9lectrique. La 4 E-Tech semble bien l\u2019inspirer, au point m\u00eame d\u2019en proposer une exclusivit\u00e9 Web au 1\/18e, limit\u00e9e \u00e0 300 exemplaires. \u00a0 D\u00e9couverte ou non Les collectionneurs de miniatures repr\u00e9sentant des voitures \u00e9lectriques sont-ils nombreux ? [\u2026] <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/norev-reproduit-la-renault-4-e-tech-au-1-64-1-43-et-1-18\/\"><\/a><\/p>\n","protected":false},"author":3,"featured_media":304979,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-304978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avem"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=304978"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/304978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/304979"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=304978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=304978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=304978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}