{"id":305675,"date":"2025-07-11T09:20:05","date_gmt":"2025-07-11T07:20:05","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one\/"},"modified":"2025-07-11T09:20:05","modified_gmt":"2025-07-11T07:20:05","slug":"1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one\/","title":{"rendered":"1 000 km en 24 heures avec une moto \u00e9lectrique LiveWire One"},"content":{"rendered":"<p><img width=\"1000\" height=\"563\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"La LiveWire One de J\u00e9r\u00e9mie \u00e0 la Dutch 1000 2025\" decoding=\"async\" fetchpriority=\"high\" srcset=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one.jpg 1000w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one-1.jpg 300w, https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one-2.jpg 998w, https:\/\/www.avem.fr\/wp-content\/uploads\/2025\/07\/ACTF0711_Dutch1000d-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>Cofondateur et directeur R&#038;D des e-Garages Revolte, J\u00e9r\u00e9mie Noirot vient de participer pour la cinqui\u00e8me ann\u00e9e cons\u00e9cutive \u00e0 la Dutch 1000. Pour l\u2019\u00e9dition 2025, c\u2019est avec une Livewire One pr\u00eat\u00e9e par la marque. Il raconte aux lecteurs de l\u2019Avem. \u00a0 Apr\u00e8s 3 ans en motos \u00e9lectriques Energica Programm\u00e9e cette ann\u00e9e [\u2026] <a href=https:\/\/www.avem.fr\/2025\/07\/11\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one\/ target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"La LiveWire One de J\u00e9r\u00e9mie \u00e0 la Dutch 1000 2025\" \/>Cofondateur et directeur R&amp;D des e-Garages Revolte, J\u00e9r\u00e9mie Noirot vient de participer pour la cinqui\u00e8me ann\u00e9e cons\u00e9cutive \u00e0 la Dutch 1000. Pour l\u2019\u00e9dition 2025, c\u2019est avec une Livewire One pr\u00eat\u00e9e par la marque. Il raconte aux lecteurs de l\u2019Avem. \u00a0 Apr\u00e8s 3 ans en motos \u00e9lectriques Energica Programm\u00e9e cette ann\u00e9e [\u2026] <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/1-000-km-en-24-heures-avec-une-moto-electrique-livewire-one\/\"><\/a><\/p>\n","protected":false},"author":3,"featured_media":305676,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-305675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avem"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/305675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=305675"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/305675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/305676"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=305675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=305675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=305675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}