{"id":316349,"date":"2026-02-02T09:00:08","date_gmt":"2026-02-02T08:00:08","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/les-voitures-electriques-xiaomi-aux-usa-completement-faux-la-marque-douche-les-espoirs-des-americains\/"},"modified":"2026-02-02T09:00:08","modified_gmt":"2026-02-02T08:00:08","slug":"les-voitures-electriques-xiaomi-aux-usa-completement-faux-la-marque-douche-les-espoirs-des-americains","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/les-voitures-electriques-xiaomi-aux-usa-completement-faux-la-marque-douche-les-espoirs-des-americains\/","title":{"rendered":"Les voitures \u00e9lectriques Xiaomi aux USA ? \u00ab Compl\u00e8tement faux \u00bb : la marque douche les espoirs des am\u00e9ricains"},"content":{"rendered":"<p><img width=\"1200\" height=\"675\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2026\/02\/les-voitures-electriques-xiaomi-aux-usa-completement-faux-la-marque-douche-les-espoirs-des-americains.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/<br \/>\nXiaomi va-t-il envahir les routes am\u00e9ricaines avec Ford ? La r\u00e9ponse est tomb\u00e9e, et elle est claire. Apr\u00e8s des rumeurs persistantes de coentreprise, le g\u00e9ant chinois a mis les points sur les i : pas de partenariat, pas de voitures, et surtout, aucune intention de s&rsquo;installer aux \u00c9tats-Unis.<br \/>\n <a href=https:\/\/www.frandroid.com\/marques\/xiaomi\/2962461_les-voitures-electriques-xiaomi-aux-usa-completement-faux-la-marque-douche-les-espoirs-des-americains target='blank'>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;img width=&quot;1200&quot; height=&quot;675&quot; src=&quot;https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2026\/02\/les-voitures-electriques-xiaomi-aux-usa-completement-faux-la-marque-douche-les-espoirs-des-americains.jpg&quot; class=&quot;attachment-full size-full wp-post-image&quot; alt=&quot;&quot; decoding=&quot;async&quot; loading=&quot;lazy&quot; \/<br \/>\nXiaomi va-t-il envahir les routes am\u00e9ricaines avec Ford ? La r\u00e9ponse est tomb\u00e9e, et elle est claire. Apr\u00e8s des rumeurs persistantes de coentreprise, le g\u00e9ant chinois a mis les points sur les i : pas de partenariat, pas de voitures, et surtout, aucune intention de s&rsquo;installer aux \u00c9tats-Unis.\n<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/les-voitures-electriques-xiaomi-aux-usa-completement-faux-la-marque-douche-les-espoirs-des-americains\/\"><\/a><\/p>\n","protected":false},"author":6,"featured_media":316350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-316349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frandroid"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/316349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=316349"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/316349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/316350"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=316349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=316349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=316349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}