{"id":316357,"date":"2026-02-02T11:23:42","date_gmt":"2026-02-02T10:23:42","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/le-patron-de-volkswagen-prend-une-decision-radicale-fabriquer-les-voitures-en-chine-pour-certaines-regions-du-monde\/"},"modified":"2026-02-02T11:23:42","modified_gmt":"2026-02-02T10:23:42","slug":"le-patron-de-volkswagen-prend-une-decision-radicale-fabriquer-les-voitures-en-chine-pour-certaines-regions-du-monde","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/le-patron-de-volkswagen-prend-une-decision-radicale-fabriquer-les-voitures-en-chine-pour-certaines-regions-du-monde\/","title":{"rendered":"Le patron de Volkswagen prend une d\u00e9cision radicale : fabriquer les voitures en Chine pour certaines r\u00e9gions du monde"},"content":{"rendered":"<p><img loading=\"lazy\" width=\"1200\" height=\"675\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2026\/02\/le-patron-de-volkswagen-prend-une-decision-radicale-fabriquer-les-voitures-en-chine-pour-certaines-regions-du-monde.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" decoding=\"async\" \/<br \/>\nSi de plus en plus de constructeurs chinois vont produire leurs voitures \u00e9lectriques localement et r\u00e9duire les exportations, Volkswagen prend le contre-pied. La marque allemande veut accro\u00eetre ces derni\u00e8res afin d\u2019inonder le march\u00e9 mondial.<br \/>\n <a href=https:\/\/www.frandroid.com\/marques\/volkswagen\/2962625_le-patron-de-volkswagen-prend-une-decision-radicale-fabriquer-les-voitures-en-chine-pour-certaines-regions-du-monde target='blank'>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;img width=&quot;1200&quot; height=&quot;675&quot; src=&quot;https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2026\/02\/le-patron-de-volkswagen-prend-une-decision-radicale-fabriquer-les-voitures-en-chine-pour-certaines-regions-du-monde.jpg&quot; class=&quot;attachment-full size-full wp-post-image&quot; alt=&quot;&quot; decoding=&quot;async&quot; \/<br \/>\nSi de plus en plus de constructeurs chinois vont produire leurs voitures \u00e9lectriques localement et r\u00e9duire les exportations, Volkswagen prend le contre-pied. La marque allemande veut accro\u00eetre ces derni\u00e8res afin d\u2019inonder le march\u00e9 mondial.\n<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/le-patron-de-volkswagen-prend-une-decision-radicale-fabriquer-les-voitures-en-chine-pour-certaines-regions-du-monde\/\"><\/a><\/p>\n","protected":false},"author":6,"featured_media":316358,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-316357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frandroid"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/316357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=316357"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/316357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/316358"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=316357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=316357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=316357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}