{"id":316386,"date":"2026-02-02T15:06:02","date_gmt":"2026-02-02T14:06:02","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/la-renault-5-electrique-est-elle-en-train-de-rattraper-la-clio-thermique\/"},"modified":"2026-02-02T15:06:02","modified_gmt":"2026-02-02T14:06:02","slug":"la-renault-5-electrique-est-elle-en-train-de-rattraper-la-clio-thermique","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/la-renault-5-electrique-est-elle-en-train-de-rattraper-la-clio-thermique\/","title":{"rendered":"La Renault 5 \u00e9lectrique est-elle en train de rattraper la Clio thermique\u00a0?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2026\/02\/la-renault-5-electrique-est-elle-en-train-de-rattraper-la-clio-thermique.jpg\" alt=\"caradisiac\" ><br \/>La Renault 5 \u00e9lectrique d\u00e9marre l\u2019ann\u00e9e 2026 sur les chapeaux de roues en France et commence s\u00e9rieusement \u00e0 se rapprocher des chiffres de vente des mod\u00e8les thermiques les plus vendus du pays. Va-t-elle finir par battre sa s\u0153ur ? Pour la Renault 4, en revanche, \u00e7a coince un peu pour le moment. <a href=https:\/\/www.caradisiac.com\/la-renault-5-electrique-est-elle-en-train-de-rattraper-la-clio-thermique-220208.htm#xtor=RSS-40 target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2026\/02\/la-renault-5-electrique-est-elle-en-train-de-rattraper-la-clio-thermique.jpg\" alt=\"caradisiac\"><br \/>La Renault 5 \u00e9lectrique d\u00e9marre l\u2019ann\u00e9e 2026 sur les chapeaux de roues en France et commence s\u00e9rieusement \u00e0 se rapprocher des chiffres de vente des mod\u00e8les thermiques les plus vendus du pays. Va-t-elle finir par battre sa s\u0153ur ? Pour la Renault 4, en revanche, \u00e7a coince un peu pour le moment.<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/la-renault-5-electrique-est-elle-en-train-de-rattraper-la-clio-thermique\/\"><\/a><\/p>\n","protected":false},"author":11,"featured_media":316387,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-316386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caradisiac"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/316386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=316386"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/316386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/316387"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=316386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=316386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=316386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}