{"id":316715,"date":"2026-02-07T09:00:06","date_gmt":"2026-02-07T08:00:06","guid":{"rendered":"https:\/\/www.evearly.news\/fr\/future-bmw-i3-vs-future-mercedes-classe-c-eq-1er-duel-sous-haute-tension\/"},"modified":"2026-02-07T09:00:06","modified_gmt":"2026-02-07T08:00:06","slug":"future-bmw-i3-vs-future-mercedes-classe-c-eq-1er-duel-sous-haute-tension","status":"publish","type":"post","link":"https:\/\/www.evearly.news\/fr\/future-bmw-i3-vs-future-mercedes-classe-c-eq-1er-duel-sous-haute-tension\/","title":{"rendered":"Future BMW i3 vs future Mercedes Classe C EQ : 1er duel sous haute tension"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.evearly.news\/fr\/wp-content\/uploads\/sites\/6\/2026\/02\/future-bmw-i3-vs-future-mercedes-classe-c-eq-1er-duel-sous-haute-tension.webp\" alt=\"auto-moto\"><br \/>De quel bois se chaufferont les berlines 100% \u00e9lectriques les plus attendues en 2026 ? Premiers \u00e9l\u00e9ments de r\u00e9ponse en opposant la BMW i3 \u00e0 la Mercedes Classe C EQ. <a href=https:\/\/www.auto-moto.com\/berline-familiale\/future-bmw-i3-vs-future-mercedes-classe-c-eq-1er-duel-sous-haute-tension-69423 target=blank>Lire la suite&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De quel bois se chaufferont les berlines 100% \u00e9lectriques les plus attendues en 2026 ? Premiers \u00e9l\u00e9ments de r\u00e9ponse en opposant la BMW i3 \u00e0 la Mercedes Classe C EQ&#8230;. <a class=\"continue-reading-link\" href=\"https:\/\/www.evearly.news\/fr\/future-bmw-i3-vs-future-mercedes-classe-c-eq-1er-duel-sous-haute-tension\/\"><\/a><\/p>\n","protected":false},"author":9,"featured_media":316716,"comment_status":"closed","ping_status":"open","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-316715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auto-moto-com"],"_links":{"self":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/316715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/comments?post=316715"}],"version-history":[{"count":0,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/posts\/316715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media\/316716"}],"wp:attachment":[{"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/media?parent=316715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/categories?post=316715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evearly.news\/fr\/wp-json\/wp\/v2\/tags?post=316715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}